{"id":2018,"date":"2026-02-11T15:51:39","date_gmt":"2026-02-11T14:51:39","guid":{"rendered":"https:\/\/finquessegarra.com\/?post_type=podcast-segarra&#038;p=2018"},"modified":"2026-05-08T15:56:12","modified_gmt":"2026-05-08T13:56:12","slug":"acceso-a-la-vivienda-en-espana","status":"publish","type":"podcast-segarra","link":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/","title":{"rendered":"P\u00f3dcast 14 &#8211; Acceso a la vivienda en Espa\u00f1a"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.youtube.com\/@finquessegarra32\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Acceso a la vivienda en Espa\u00f1a: C\u00f3mo afecta la nueva ley a inquilinos y propietarios\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/ZQGIf0lLlMM?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sobre el p\u00f3dcast<\/h2>\n\n\n\n<p>En este episodio del podcast de Finques Segarra, analizamos la situaci\u00f3n actual de la vivienda en Espa\u00f1a y las perspectivas reales del mercado inmobiliario:<\/p>\n\n\n\n<p><strong>Temas destacados en este episodio:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfQu\u00e9 impacto tiene la nueva Ley de la Vivienda en el acceso a la vivienda y en los precios, especialmente en Catalu\u00f1a? <\/li>\n\n\n\n<li>\u00bfEst\u00e1 realmente mejorando la accesibilidad a la vivienda o la inseguridad jur\u00eddica est\u00e1 generando miedo entre los propietarios?<\/li>\n\n\n\n<li>\u00bfQu\u00e9 consecuencias tiene la no-pr\u00f3rroga de los contratos y c\u00f3mo est\u00e1 afectando a la relaci\u00f3n entre inquilinos y propietarios?<\/li>\n\n\n\n<li>\u00bfLos pisos tur\u00edsticos est\u00e1n dificultando el acceso a viviendas habituales?<\/li>\n<\/ul>\n\n\n\n<p><strong>Sobre el invitado:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Josep Maria Rius:<\/strong>\u00a0Agente inmobiliario y CEO de Finques Rius, aporta su visi\u00f3n del mercado inmobiliario actual y las previsiones para los pr\u00f3ximos a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<p><strong>Escucha el episodio completo<\/strong> y descubre c\u00f3mo afecta la nueva ley a inquilinos y propietarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este episodio del podcast de Finques Segarra, analizamos la situaci\u00f3n actual de la vivienda en Espa\u00f1a y las perspectivas reales del mercado inmobiliario.<\/p>\n","protected":false},"featured_media":2020,"parent":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-2018","podcast-segarra","type-podcast-segarra","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u00f3dcast 14 - Acceso a la vivienda en Espa\u00f1a - \ud83e\udd47 Inmobiliaria Vendrell - Comarruga<\/title>\n<meta name=\"description\" content=\"En este episodio del podcast, analizamos la situaci\u00f3n actual de la vivienda en Espa\u00f1a y las perspectivas reales del mercado inmobiliario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00f3dcast 14 - Acceso a la vivienda en Espa\u00f1a - \ud83e\udd47 Inmobiliaria Vendrell - Comarruga\" \/>\n<meta property=\"og:description\" content=\"En este episodio del podcast, analizamos la situaci\u00f3n actual de la vivienda en Espa\u00f1a y las perspectivas reales del mercado inmobiliario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"\ud83e\udd47 Inmobiliaria Vendrell - Comarruga\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T13:56:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/finquessegarra.com\/wp-content\/uploads\/2026\/05\/PODCAST-SEG-Portadas-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/\",\"url\":\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/\",\"name\":\"P\u00f3dcast 14 - Acceso a la vivienda en Espa\u00f1a - \ud83e\udd47 Inmobiliaria Vendrell - Comarruga\",\"isPartOf\":{\"@id\":\"https:\/\/finquessegarra.com\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/finquessegarra.com\/wp-content\/uploads\/2026\/05\/PODCAST-SEG-Portadas-2.png\",\"datePublished\":\"2026-02-11T14:51:39+00:00\",\"dateModified\":\"2026-05-08T13:56:12+00:00\",\"description\":\"En este episodio del podcast, analizamos la situaci\u00f3n actual de la vivienda en Espa\u00f1a y las perspectivas reales del mercado inmobiliario.\",\"breadcrumb\":{\"@id\":\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#primaryimage\",\"url\":\"https:\/\/finquessegarra.com\/wp-content\/uploads\/2026\/05\/PODCAST-SEG-Portadas-2.png\",\"contentUrl\":\"https:\/\/finquessegarra.com\/wp-content\/uploads\/2026\/05\/PODCAST-SEG-Portadas-2.png\",\"width\":1920,\"height\":1080,\"caption\":\"Acceso a la vivienda en Espa\u00f1a: C\u00f3mo afecta la nueva ley a inquilinos y propietarios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/finquessegarra.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00f3dcast 14 &#8211; Acceso a la vivienda en Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/finquessegarra.com\/ca\/#website\",\"url\":\"https:\/\/finquessegarra.com\/ca\/\",\"name\":\"\ud83e\udd47 Inmobiliaria Vendrell - Comarruga\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/finquessegarra.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00f3dcast 14 - Acceso a la vivienda en Espa\u00f1a - \ud83e\udd47 Inmobiliaria Vendrell - Comarruga","description":"En este episodio del podcast, analizamos la situaci\u00f3n actual de la vivienda en Espa\u00f1a y las perspectivas reales del mercado inmobiliario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/","og_locale":"ca_ES","og_type":"article","og_title":"P\u00f3dcast 14 - Acceso a la vivienda en Espa\u00f1a - \ud83e\udd47 Inmobiliaria Vendrell - Comarruga","og_description":"En este episodio del podcast, analizamos la situaci\u00f3n actual de la vivienda en Espa\u00f1a y las perspectivas reales del mercado inmobiliario.","og_url":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/","og_site_name":"\ud83e\udd47 Inmobiliaria Vendrell - Comarruga","article_modified_time":"2026-05-08T13:56:12+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/finquessegarra.com\/wp-content\/uploads\/2026\/05\/PODCAST-SEG-Portadas-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/","url":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/","name":"P\u00f3dcast 14 - Acceso a la vivienda en Espa\u00f1a - \ud83e\udd47 Inmobiliaria Vendrell - Comarruga","isPartOf":{"@id":"https:\/\/finquessegarra.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/finquessegarra.com\/wp-content\/uploads\/2026\/05\/PODCAST-SEG-Portadas-2.png","datePublished":"2026-02-11T14:51:39+00:00","dateModified":"2026-05-08T13:56:12+00:00","description":"En este episodio del podcast, analizamos la situaci\u00f3n actual de la vivienda en Espa\u00f1a y las perspectivas reales del mercado inmobiliario.","breadcrumb":{"@id":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#primaryimage","url":"https:\/\/finquessegarra.com\/wp-content\/uploads\/2026\/05\/PODCAST-SEG-Portadas-2.png","contentUrl":"https:\/\/finquessegarra.com\/wp-content\/uploads\/2026\/05\/PODCAST-SEG-Portadas-2.png","width":1920,"height":1080,"caption":"Acceso a la vivienda en Espa\u00f1a: C\u00f3mo afecta la nueva ley a inquilinos y propietarios"},{"@type":"BreadcrumbList","@id":"https:\/\/finquessegarra.com\/ca\/podcast-segarra\/acceso-a-la-vivienda-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/finquessegarra.com\/ca\/"},{"@type":"ListItem","position":2,"name":"P\u00f3dcast 14 &#8211; Acceso a la vivienda en Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/finquessegarra.com\/ca\/#website","url":"https:\/\/finquessegarra.com\/ca\/","name":"\ud83e\udd47 Inmobiliaria Vendrell - Comarruga","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/finquessegarra.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/finquessegarra.com\/ca\/wp-json\/wp\/v2\/podcast-segarra\/2018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finquessegarra.com\/ca\/wp-json\/wp\/v2\/podcast-segarra"}],"about":[{"href":"https:\/\/finquessegarra.com\/ca\/wp-json\/wp\/v2\/types\/podcast-segarra"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finquessegarra.com\/ca\/wp-json\/wp\/v2\/media\/2020"}],"wp:attachment":[{"href":"https:\/\/finquessegarra.com\/ca\/wp-json\/wp\/v2\/media?parent=2018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}